{"id":20,"count":11,"description":"","link":"https:\/\/osebergvikingarv.no\/eng\/category\/research\/","name":"Research","slug":"research","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/osebergvikingarv.no\/eng\/category\/research\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/20\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/category\\\/research\\\/#listItem\",\"name\":\"Research\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/category\\\/research\\\/#listItem\",\"position\":2,\"name\":\"Research\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/20\\\/#collectionpage\",\"url\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/20\\\/\",\"name\":\"Research - Oseberg Viking Heritage\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/20\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/#organization\",\"name\":\"Oseberg Viking Heritage\",\"description\":\"from find to common understanding\",\"url\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/11\\\/cropped-cropped-oseberg-vikingarv-logo2-engelsk-copy.png\",\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/20\\\/#organizationLogo\",\"width\":500,\"height\":119},\"image\":{\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/20\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/#website\",\"url\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/\",\"name\":\"Oseberg Viking Heritage\",\"description\":\"from find to common understanding\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/osebergvikingarv.no\\\/eng\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Research - Oseberg Viking Heritage","description":"","canonical_url":"https:\/\/osebergvikingarv.no\/eng\/category\/research\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/osebergvikingarv.no\/eng\/wp-json\/wp\/v2\/categories\/20\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/osebergvikingarv.no\/eng#listItem","position":1,"name":"Home","item":"https:\/\/osebergvikingarv.no\/eng","nextItem":{"@type":"ListItem","@id":"https:\/\/osebergvikingarv.no\/eng\/category\/research\/#listItem","name":"Research"}},{"@type":"ListItem","@id":"https:\/\/osebergvikingarv.no\/eng\/category\/research\/#listItem","position":2,"name":"Research","previousItem":{"@type":"ListItem","@id":"https:\/\/osebergvikingarv.no\/eng#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/osebergvikingarv.no\/eng\/wp-json\/wp\/v2\/categories\/20\/#collectionpage","url":"https:\/\/osebergvikingarv.no\/eng\/wp-json\/wp\/v2\/categories\/20\/","name":"Research - Oseberg Viking Heritage","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/osebergvikingarv.no\/eng\/#website"},"breadcrumb":{"@id":"https:\/\/osebergvikingarv.no\/eng\/wp-json\/wp\/v2\/categories\/20\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/osebergvikingarv.no\/eng\/#organization","name":"Oseberg Viking Heritage","description":"from find to common understanding","url":"https:\/\/osebergvikingarv.no\/eng\/","logo":{"@type":"ImageObject","url":"https:\/\/osebergvikingarv.no\/eng\/wp-content\/uploads\/sites\/2\/2019\/11\/cropped-cropped-oseberg-vikingarv-logo2-engelsk-copy.png","@id":"https:\/\/osebergvikingarv.no\/eng\/wp-json\/wp\/v2\/categories\/20\/#organizationLogo","width":500,"height":119},"image":{"@id":"https:\/\/osebergvikingarv.no\/eng\/wp-json\/wp\/v2\/categories\/20\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/osebergvikingarv.no\/eng\/#website","url":"https:\/\/osebergvikingarv.no\/eng\/","name":"Oseberg Viking Heritage","description":"from find to common understanding","inLanguage":"en-GB","publisher":{"@id":"https:\/\/osebergvikingarv.no\/eng\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/osebergvikingarv.no\/eng\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tResearch\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/osebergvikingarv.no\/eng"},{"label":"Research","link":"https:\/\/osebergvikingarv.no\/eng\/category\/research\/"}],"_links":{"self":[{"href":"https:\/\/osebergvikingarv.no\/eng\/wp-json\/wp\/v2\/categories\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osebergvikingarv.no\/eng\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/osebergvikingarv.no\/eng\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/osebergvikingarv.no\/eng\/wp-json\/wp\/v2\/posts?categories=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}